{"id":105,"count":2,"description":"","link":"https:\/\/blogs.encamina.com\/mascrm\/tag\/portal-crm\/","name":"Portal CRM","slug":"portal-crm","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.2.1 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Portal CRM Archives - M\u00e1s CRM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.encamina.com\/mascrm\/tag\/portal-crm\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/mascrm\\\/tag\\\/portal-crm\\\/\",\"url\":\"https:\\\/\\\/blogs.encamina.com\\\/mascrm\\\/tag\\\/portal-crm\\\/\",\"name\":\"Portal CRM Archives - M\u00e1s CRM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/mascrm\\\/#website\"},\"inLanguage\":\"es\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/mascrm\\\/#website\",\"url\":\"https:\\\/\\\/blogs.encamina.com\\\/mascrm\\\/\",\"name\":\"M\u00e1s CRM\",\"description\":\"Reflexiones y apuntes sobre  arquitectura, consultor\u00eda y gesti\u00f3n proyectos CRM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.encamina.com\\\/mascrm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Portal CRM Archives - M\u00e1s CRM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.encamina.com\/mascrm\/tag\/portal-crm\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.encamina.com\/mascrm\/tag\/portal-crm\/","url":"https:\/\/blogs.encamina.com\/mascrm\/tag\/portal-crm\/","name":"Portal CRM Archives - M\u00e1s CRM","isPartOf":{"@id":"https:\/\/blogs.encamina.com\/mascrm\/#website"},"inLanguage":"es"},{"@type":"WebSite","@id":"https:\/\/blogs.encamina.com\/mascrm\/#website","url":"https:\/\/blogs.encamina.com\/mascrm\/","name":"M\u00e1s CRM","description":"Reflexiones y apuntes sobre  arquitectura, consultor\u00eda y gesti\u00f3n proyectos CRM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.encamina.com\/mascrm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/blogs.encamina.com\/mascrm\/wp-json\/wp\/v2\/tags\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.encamina.com\/mascrm\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.encamina.com\/mascrm\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.encamina.com\/mascrm\/wp-json\/wp\/v2\/posts?tags=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}