{"id":5222,"date":"2024-03-07T16:45:27","date_gmt":"2024-03-07T15:45:27","guid":{"rendered":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/?p=5222"},"modified":"2024-04-02T11:30:37","modified_gmt":"2024-04-02T10:30:37","slug":"revive-la-emocion-del-propulsion-lab-vi","status":"publish","type":"post","link":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/","title":{"rendered":"Revivimos la emoci\u00f3n del Propulsion Lab VI"},"content":{"rendered":"<p><div id=\"attachment_5258\" style=\"width: 2570px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5258\" class=\"wp-image-5258 size-full\" src=\"http:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-scaled.jpg 2560w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-300x225.jpg 300w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-1024x768.jpg 1024w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-768x576.jpg 768w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-1536x1152.jpg 1536w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-2048x1536.jpg 2048w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-610x458.jpg 610w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><p id=\"caption-attachment-5258\" class=\"wp-caption-text\">El presidente de Microsoft, Alberto Granados, particip\u00f3 en el Propulsion Lab VI, aportando su visi\u00f3n sobre el futuro de la tecnolog\u00eda<\/p><\/div><\/p>\n<p>Ayer el Ateneo de Valencia se convirti\u00f3 en el epicentro de la innovaci\u00f3n, al albergar nuestro Propulsion Lab VI \ud83d\ude42 En esta sexta edici\u00f3n quisimos reimaginar el futuro de los sistemas de informaci\u00f3n (SI) y las aplicaciones empresariales, y para ello reunimos a l\u00edderes, expertos y apasionados de la tecnolog\u00eda con muchas ganas de aprender e impulsar la innovaci\u00f3n de sus empresas.<\/p>\n<p><!--more--><\/p>\n<p>Tras una keynote de nuestro CTIO,\u00a0 <strong>Alberto D\u00edaz<\/strong>, dedicada al impacto de la Inteligencia Artificial en la competitividad empresarial, los asistentes se repartieron en equipos tres talleres dedicado a un aspecto fundamental de la IA.<\/p>\n<p>Desde debatir sobre los futuros \u00abbuilding blocks\u00bb de los SI, liderado por <strong>David Vidal<\/strong>, hasta sumergirse en la integraci\u00f3n omnipresente de la IA en todos los aspectos organizativos con <strong>Jonathan Manrique<\/strong>, el viaje fue fascinante. El tercer taller, liderado por <strong>Borja Piris<\/strong>, nos transport\u00f3 a la vanguardia de las experiencias del cliente, todo ello acompa\u00f1ado con catas de productos regionales que representaban las caracter\u00edsticas de la IA.<\/p>\n<p><div id=\"attachment_5241\" style=\"width: 1930px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5241\" class=\"wp-image-5241 size-full\" src=\"http:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095220-b8af4475-scaled-e1709825749120.jpeg\" alt=\"\" width=\"1920\" height=\"1501\" srcset=\"https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095220-b8af4475-scaled-e1709825749120.jpeg 1920w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095220-b8af4475-scaled-e1709825749120-300x235.jpeg 300w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095220-b8af4475-scaled-e1709825749120-1024x801.jpeg 1024w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095220-b8af4475-scaled-e1709825749120-768x600.jpeg 768w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095220-b8af4475-scaled-e1709825749120-1536x1201.jpeg 1536w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095220-b8af4475-scaled-e1709825749120-610x477.jpeg 610w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><p id=\"caption-attachment-5241\" class=\"wp-caption-text\">David Vidal en el taller de los futuros building-blocks de nuestros S.I<\/p><\/div><\/p>\n<p><div id=\"attachment_5243\" style=\"width: 1930px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5243\" class=\"wp-image-5243 size-full\" src=\"http:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095329-78e7f572-scaled-e1709825976306.jpeg\" alt=\"\" width=\"1920\" height=\"1783\" srcset=\"https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095329-78e7f572-scaled-e1709825976306.jpeg 1920w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095329-78e7f572-scaled-e1709825976306-300x279.jpeg 300w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095329-78e7f572-scaled-e1709825976306-1024x951.jpeg 1024w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095329-78e7f572-scaled-e1709825976306-768x713.jpeg 768w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095329-78e7f572-scaled-e1709825976306-1536x1426.jpeg 1536w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095329-78e7f572-scaled-e1709825976306-610x566.jpeg 610w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><p id=\"caption-attachment-5243\" class=\"wp-caption-text\">Borja Piris en el laboratorio de nuevas experiencias de cliente Everywhere-Everyway<\/p><\/div><\/p>\n<p><div id=\"attachment_5244\" style=\"width: 1930px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5244\" class=\"wp-image-5244 size-full\" src=\"http:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095318-c8ab1cb3-scaled-e1709826036247.jpeg\" alt=\"\" width=\"1920\" height=\"1472\" srcset=\"https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095318-c8ab1cb3-scaled-e1709826036247.jpeg 1920w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095318-c8ab1cb3-scaled-e1709826036247-300x230.jpeg 300w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095318-c8ab1cb3-scaled-e1709826036247-1024x785.jpeg 1024w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095318-c8ab1cb3-scaled-e1709826036247-768x589.jpeg 768w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095318-c8ab1cb3-scaled-e1709826036247-1536x1178.jpeg 1536w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-095318-c8ab1cb3-scaled-e1709826036247-610x468.jpeg 610w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><p id=\"caption-attachment-5244\" class=\"wp-caption-text\">Jonathan Manrique lider\u00f3 el taller del poder de la IA para integrar en toda la organizaci\u00f3n<\/p><\/div><\/p>\n<p>Todos estuvieron participativos, debatieron y aportaron sus ideas respecto a los casos pr\u00e1cticos dentro de sus organizaciones.<\/p>\n<p>Uno de los momentos m\u00e1s esperados fue la intervenci\u00f3n de <strong>Alberto Granados, Presidente de Microsoft Espa\u00f1a<\/strong>, quien destac\u00f3 la importancia de adoptar la IA para mantener la competitividad en la era digital y mantuvo un debate abierto con el resto de los participantes.<\/p>\n<p><div id=\"attachment_5247\" style=\"width: 1930px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5247\" class=\"wp-image-5247 size-full\" src=\"http:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-115529-904b574e-scaled-e1709826312242.jpeg\" alt=\"\" width=\"1920\" height=\"1548\" srcset=\"https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-115529-904b574e-scaled-e1709826312242.jpeg 1920w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-115529-904b574e-scaled-e1709826312242-300x242.jpeg 300w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-115529-904b574e-scaled-e1709826312242-1024x826.jpeg 1024w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-115529-904b574e-scaled-e1709826312242-768x619.jpeg 768w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-115529-904b574e-scaled-e1709826312242-1536x1238.jpeg 1536w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-115529-904b574e-scaled-e1709826312242-610x492.jpeg 610w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><p id=\"caption-attachment-5247\" class=\"wp-caption-text\">El presidente de Microsoft, Alberto Granados, interactuando con el p\u00fablico, muy interesado en los proyectos de IA en el futuro<\/p><\/div><\/p>\n<p>Se hace eco de la participaci\u00f3n de Alberto Granados en nuestro PROPULSION LAB, Channel Partner hablando <a href=\"https:\/\/www.channelpartner.es\/distribuidores\/alberto-granados-microsoft-la-parte-etica-y-responsable-de-la-ia-no-es-un-selfie-no-es-un-ethicwashing\/\">sobre la parte \u00e9tica de la IA<\/a>.<\/p>\n<p>La emoci\u00f3n alcanz\u00f3 su punto m\u00e1ximo con la entrega de premios al\u00a0 equipo m\u00e1s visionario, al m\u00e1s colaborativo y al mas pr\u00e1ctico y ejecutivo,\u00a0 por parte de Alberto Granados y de <strong>Jos\u00e9 Manuel Garc\u00eda Duarte<\/strong>, Director general de Tecnolog\u00edas de la Informaci\u00f3n y\u00a0 Comunicaciones de la Generalitat Valenciana.<\/p>\n<p><div id=\"attachment_5249\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5249\" class=\"wp-image-5249 size-full\" src=\"http:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240307-150448-33ddb8e6.jpeg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240307-150448-33ddb8e6.jpeg 1024w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240307-150448-33ddb8e6-300x225.jpeg 300w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240307-150448-33ddb8e6-768x576.jpeg 768w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240307-150448-33ddb8e6-610x458.jpeg 610w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-5249\" class=\"wp-caption-text\">Premio al equipo m\u00e1s creativo y visionario<\/p><\/div><\/p>\n<p>&nbsp;<\/p>\n<p><div id=\"attachment_5251\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5251\" class=\"wp-image-5251 size-full\" src=\"http:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240307-150457-03d754f3.jpeg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240307-150457-03d754f3.jpeg 1024w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240307-150457-03d754f3-300x225.jpeg 300w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240307-150457-03d754f3-768x576.jpeg 768w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240307-150457-03d754f3-610x458.jpeg 610w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-5251\" class=\"wp-caption-text\">Premio al equipo m\u00e1s comunicativo y colaborativo<\/p><\/div><\/p>\n<p>Y como ya es tradici\u00f3n en nuestros Propulsions, la jornada tuvo traca final \ud83d\ude05 al presenciar la masclet\u00e1 desde el balc\u00f3n del Ateneo Mercantil de Valencia.<\/p>\n<p>&nbsp;<\/p>\n<p><div id=\"attachment_5257\" style=\"width: 1930px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5257\" class=\"size-full wp-image-5257\" src=\"http:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-133224-565ae426-scaled.jpeg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-133224-565ae426-scaled.jpeg 1920w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-133224-565ae426-225x300.jpeg 225w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-133224-565ae426-768x1024.jpeg 768w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-133224-565ae426-1152x1536.jpeg 1152w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-133224-565ae426-1536x2048.jpeg 1536w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-133224-565ae426-610x813.jpeg 610w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><p id=\"caption-attachment-5257\" class=\"wp-caption-text\">L\u00edderes y mentores preparados para culminar la jornada a ritmo de la masclet\u00e1<\/p><\/div><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5262\" src=\"http:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/MicrosoftTeams-image-265-scaled.jpg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/MicrosoftTeams-image-265-scaled.jpg 1920w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/MicrosoftTeams-image-265-225x300.jpg 225w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/MicrosoftTeams-image-265-768x1024.jpg 768w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/MicrosoftTeams-image-265-1152x1536.jpg 1152w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/MicrosoftTeams-image-265-1536x2048.jpg 1536w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/MicrosoftTeams-image-265-610x813.jpg 610w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p>El Propulsion Lab VI no fue simplemente un evento; <strong>fue una ventana al futuro de la tecnolog\u00eda y los negocios<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5240 size-full\" src=\"http:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-111632-6afb9e28-scaled-e1709825562385.jpeg\" alt=\"\" width=\"1723\" height=\"891\" srcset=\"https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-111632-6afb9e28-scaled-e1709825562385.jpeg 1723w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-111632-6afb9e28-scaled-e1709825562385-300x155.jpeg 300w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-111632-6afb9e28-scaled-e1709825562385-1024x530.jpeg 1024w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-111632-6afb9e28-scaled-e1709825562385-768x397.jpeg 768w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-111632-6afb9e28-scaled-e1709825562385-1536x794.jpeg 1536w, https:\/\/encaminablogs.wpenginepowered.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/imagen-20240306-111632-6afb9e28-scaled-e1709825562385-610x315.jpeg 610w\" sizes=\"auto, (max-width: 1723px) 100vw, 1723px\" \/><\/p>\n<p>Agradecemos profundamente a todos nuestros clientes que hayan hecho posible este evento. Gracias, de coraz\u00f3n, por hacer que el Propulsion Lab VI haya sido un \u00e9xito un a\u00f1o m\u00e1s \ud83d\ude0d<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/youtu.be\/Bf-ZkZDEhHE?si=3DyNxK-bH1zY3ACH\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5278\" src=\"http:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/PROPULSION-LAB-BANNER.gif\" alt=\"\" width=\"840\" height=\"275\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>Tres equipos exploraron tres laboratorios, cada uno dedicado a un aspecto fundamental de la IA. Guiados por mentores destacados de ENCAMINA, los participantes se aventuraron en temas como los agentes inteligentes, la integraci\u00f3n de la IA en toda la organizaci\u00f3n y las nuevas experiencias del cliente. <a href=\"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":222,"featured_media":5258,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65,101,90,107],"tags":[98,134,135,120,129,136,124,132,121,85,137,125,100],"class_list":["post-5222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-encamina","category-innovacion","category-inteligencia-artificial","category-noticia","tag-big-data","tag-copilot","tag-copilot-365","tag-enagas","tag-encamina","tag-futuro","tag-innovacion","tag-inteligencia-artificial","tag-microsoft","tag-office-365-f1","tag-propulsion","tag-talento-tecnologico","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.2.1 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Revivimos la emoci\u00f3n del Propulsion Lab VI | ENCAMINA se Mueve<\/title>\n<meta name=\"description\" content=\"Tres equipos exploraron tres laboratorios, cada uno dedicado a un aspecto fundamental de la IA. Guiados por mentores destacados de ENCAMINA, los participantes se aventuraron en temas como los agentes inteligentes, la integraci\u00f3n de la IA en toda la organizaci\u00f3n y las nuevas experiencias del cliente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revivimos la emoci\u00f3n del Propulsion Lab VI\" \/>\n<meta property=\"og:description\" content=\"Tres equipos exploraron tres laboratorios, cada uno dedicado a un aspecto fundamental de la IA. Guiados por mentores destacados de ENCAMINA, los participantes se aventuraron en temas como los agentes inteligentes, la integraci\u00f3n de la IA en toda la organizaci\u00f3n y las nuevas experiencias del cliente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/\" \/>\n<meta property=\"og:site_name\" content=\"ENCAMINA se Mueve\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-07T15:45:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-02T10:30:37+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patricia Cabezas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patricia Cabezas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/revive-la-emocion-del-propulsion-lab-vi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/revive-la-emocion-del-propulsion-lab-vi\\\/\"},\"author\":{\"name\":\"Patricia Cabezas\",\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/#\\\/schema\\\/person\\\/87ed06b4636b718802fa0fa10c60457f\"},\"headline\":\"Revivimos la emoci\u00f3n del Propulsion Lab VI\",\"datePublished\":\"2024-03-07T15:45:27+00:00\",\"dateModified\":\"2024-04-02T10:30:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/revive-la-emocion-del-propulsion-lab-vi\\\/\"},\"wordCount\":580,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/revive-la-emocion-del-propulsion-lab-vi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/03\\\/Alberto-Granados-Propulsion-Lab-scaled.jpg\",\"keywords\":[\"big data\",\"copilot\",\"copilot 365\",\"enag\u00e1s\",\"encamina\",\"futuro\",\"innovaci\u00f3n\",\"inteligencia artificial\",\"microsoft\",\"Office 365 F1\",\"propulsion\",\"talento tecnol\u00f3gico\",\"tecnolog\u00eda\"],\"articleSection\":[\"ENCAMINA\",\"Innovaci\u00f3n\",\"Inteligencia Artificial\",\"Noticia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/revive-la-emocion-del-propulsion-lab-vi\\\/\",\"url\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/revive-la-emocion-del-propulsion-lab-vi\\\/\",\"name\":\"Revivimos la emoci\u00f3n del Propulsion Lab VI | ENCAMINA se Mueve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/revive-la-emocion-del-propulsion-lab-vi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/revive-la-emocion-del-propulsion-lab-vi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/03\\\/Alberto-Granados-Propulsion-Lab-scaled.jpg\",\"datePublished\":\"2024-03-07T15:45:27+00:00\",\"dateModified\":\"2024-04-02T10:30:37+00:00\",\"description\":\"Tres equipos exploraron tres laboratorios, cada uno dedicado a un aspecto fundamental de la IA. Guiados por mentores destacados de ENCAMINA, los participantes se aventuraron en temas como los agentes inteligentes, la integraci\u00f3n de la IA en toda la organizaci\u00f3n y las nuevas experiencias del cliente.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/revive-la-emocion-del-propulsion-lab-vi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/revive-la-emocion-del-propulsion-lab-vi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/03\\\/Alberto-Granados-Propulsion-Lab-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/03\\\/Alberto-Granados-Propulsion-Lab-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/#website\",\"url\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/\",\"name\":\"ENCAMINA se Mueve\",\"description\":\"Todo lo que se cuece en nuestro equipo: formaciones, charlas, webcasts, talleres...\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/#organization\",\"name\":\"ENCAMINA\",\"url\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2018\\\/10\\\/Logo_ENCAMINA_sin-claim.png\",\"contentUrl\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2018\\\/10\\\/Logo_ENCAMINA_sin-claim.png\",\"width\":409,\"height\":77,\"caption\":\"ENCAMINA\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/#\\\/schema\\\/person\\\/87ed06b4636b718802fa0fa10c60457f\",\"name\":\"Patricia Cabezas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d3c30d0b59887e14af0c25391ea036ac7b459f559ef19b6a1e8dec568c21cd8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d3c30d0b59887e14af0c25391ea036ac7b459f559ef19b6a1e8dec568c21cd8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d3c30d0b59887e14af0c25391ea036ac7b459f559ef19b6a1e8dec568c21cd8?s=96&d=mm&r=g\",\"caption\":\"Patricia Cabezas\"},\"description\":\"Publicista ordenando briefs y desordenando ideas en el departamento de Marketing de ENCAMINA. Generosa de sonrisas, amante de proyectos que conectan personas. Aventurera, feliz con vistas al horizonte.\",\"url\":\"https:\\\/\\\/blogs.encamina.com\\\/encamina-se-mueve\\\/author\\\/pcabezas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Revivimos la emoci\u00f3n del Propulsion Lab VI | ENCAMINA se Mueve","description":"Tres equipos exploraron tres laboratorios, cada uno dedicado a un aspecto fundamental de la IA. Guiados por mentores destacados de ENCAMINA, los participantes se aventuraron en temas como los agentes inteligentes, la integraci\u00f3n de la IA en toda la organizaci\u00f3n y las nuevas experiencias del cliente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/","og_locale":"es_ES","og_type":"article","og_title":"Revivimos la emoci\u00f3n del Propulsion Lab VI","og_description":"Tres equipos exploraron tres laboratorios, cada uno dedicado a un aspecto fundamental de la IA. Guiados por mentores destacados de ENCAMINA, los participantes se aventuraron en temas como los agentes inteligentes, la integraci\u00f3n de la IA en toda la organizaci\u00f3n y las nuevas experiencias del cliente.","og_url":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/","og_site_name":"ENCAMINA se Mueve","article_published_time":"2024-03-07T15:45:27+00:00","article_modified_time":"2024-04-02T10:30:37+00:00","og_image":[{"width":2560,"height":1920,"url":"http:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-scaled.jpg","type":"image\/jpeg"}],"author":"Patricia Cabezas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Patricia Cabezas","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/#article","isPartOf":{"@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/"},"author":{"name":"Patricia Cabezas","@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/#\/schema\/person\/87ed06b4636b718802fa0fa10c60457f"},"headline":"Revivimos la emoci\u00f3n del Propulsion Lab VI","datePublished":"2024-03-07T15:45:27+00:00","dateModified":"2024-04-02T10:30:37+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/"},"wordCount":580,"publisher":{"@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/#organization"},"image":{"@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-scaled.jpg","keywords":["big data","copilot","copilot 365","enag\u00e1s","encamina","futuro","innovaci\u00f3n","inteligencia artificial","microsoft","Office 365 F1","propulsion","talento tecnol\u00f3gico","tecnolog\u00eda"],"articleSection":["ENCAMINA","Innovaci\u00f3n","Inteligencia Artificial","Noticia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/","url":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/","name":"Revivimos la emoci\u00f3n del Propulsion Lab VI | ENCAMINA se Mueve","isPartOf":{"@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/#primaryimage"},"image":{"@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-scaled.jpg","datePublished":"2024-03-07T15:45:27+00:00","dateModified":"2024-04-02T10:30:37+00:00","description":"Tres equipos exploraron tres laboratorios, cada uno dedicado a un aspecto fundamental de la IA. Guiados por mentores destacados de ENCAMINA, los participantes se aventuraron en temas como los agentes inteligentes, la integraci\u00f3n de la IA en toda la organizaci\u00f3n y las nuevas experiencias del cliente.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/revive-la-emocion-del-propulsion-lab-vi\/#primaryimage","url":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-scaled.jpg","contentUrl":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2024\/03\/Alberto-Granados-Propulsion-Lab-scaled.jpg","width":2560,"height":1920},{"@type":"WebSite","@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/#website","url":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/","name":"ENCAMINA se Mueve","description":"Todo lo que se cuece en nuestro equipo: formaciones, charlas, webcasts, talleres...","publisher":{"@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/#organization","name":"ENCAMINA","url":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2018\/10\/Logo_ENCAMINA_sin-claim.png","contentUrl":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-content\/uploads\/sites\/4\/2018\/10\/Logo_ENCAMINA_sin-claim.png","width":409,"height":77,"caption":"ENCAMINA"},"image":{"@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/#\/schema\/person\/87ed06b4636b718802fa0fa10c60457f","name":"Patricia Cabezas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4d3c30d0b59887e14af0c25391ea036ac7b459f559ef19b6a1e8dec568c21cd8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d3c30d0b59887e14af0c25391ea036ac7b459f559ef19b6a1e8dec568c21cd8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d3c30d0b59887e14af0c25391ea036ac7b459f559ef19b6a1e8dec568c21cd8?s=96&d=mm&r=g","caption":"Patricia Cabezas"},"description":"Publicista ordenando briefs y desordenando ideas en el departamento de Marketing de ENCAMINA. Generosa de sonrisas, amante de proyectos que conectan personas. Aventurera, feliz con vistas al horizonte.","url":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/author\/pcabezas\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-json\/wp\/v2\/posts\/5222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-json\/wp\/v2\/users\/222"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-json\/wp\/v2\/comments?post=5222"}],"version-history":[{"count":0,"href":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-json\/wp\/v2\/posts\/5222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-json\/wp\/v2\/media\/5258"}],"wp:attachment":[{"href":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-json\/wp\/v2\/media?parent=5222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-json\/wp\/v2\/categories?post=5222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.encamina.com\/encamina-se-mueve\/wp-json\/wp\/v2\/tags?post=5222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}